{"id":12057,"date":"2021-11-30T21:43:52","date_gmt":"2021-11-30T23:43:52","guid":{"rendered":"https:\/\/museuflorestal.ambiente.sp.gov.br\/acervo\/?post_type=tnc_col_329_item&#038;p=12057"},"modified":"2021-11-30T21:43:53","modified_gmt":"2021-11-30T23:43:53","slug":"amostra-de-jequitiba-5","status":"publish","type":"tnc_col_329_item","link":"https:\/\/museuflorestal.ambiente.sp.gov.br\/acervo\/museu-florestal-octavio-vecchi\/amostra-de-jequitiba-5\/","title":{"rendered":"Amostra de jequitib\u00e1"},"content":{"rendered":"<p>Amostra em forma de paralelep\u00edpedo, com etiqueta em uma das faces com a inscri\u00e7\u00e3o &#8220;Jequitib\u00e1&#8221;, nome cient\u00edfico e fam\u00edlia. Na outra face h\u00e1 duas tiras de veludo vermelho. As faces laterais possuem ranhuras nas marcas dos veios da madeira.<\/p>\n","protected":false},"featured_media":12058,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","_links":{"self":[{"href":"https:\/\/museuflorestal.ambiente.sp.gov.br\/acervo\/wp-json\/wp\/v2\/tnc_col_329_item\/12057"}],"collection":[{"href":"https:\/\/museuflorestal.ambiente.sp.gov.br\/acervo\/wp-json\/wp\/v2\/tnc_col_329_item"}],"about":[{"href":"https:\/\/museuflorestal.ambiente.sp.gov.br\/acervo\/wp-json\/wp\/v2\/types\/tnc_col_329_item"}],"replies":[{"embeddable":true,"href":"https:\/\/museuflorestal.ambiente.sp.gov.br\/acervo\/wp-json\/wp\/v2\/comments?post=12057"}],"version-history":[{"count":0,"href":"https:\/\/museuflorestal.ambiente.sp.gov.br\/acervo\/wp-json\/wp\/v2\/tnc_col_329_item\/12057\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/museuflorestal.ambiente.sp.gov.br\/acervo\/wp-json\/wp\/v2\/media\/12058"}],"wp:attachment":[{"href":"https:\/\/museuflorestal.ambiente.sp.gov.br\/acervo\/wp-json\/wp\/v2\/media?parent=12057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}