{"id":12738,"date":"2021-11-30T22:01:37","date_gmt":"2021-12-01T00:01:37","guid":{"rendered":"https:\/\/museuflorestal.ambiente.sp.gov.br\/acervo\/?post_type=tnc_col_329_item&#038;p=12738"},"modified":"2021-11-30T22:01:39","modified_gmt":"2021-12-01T00:01:39","slug":"disco-de-madeira-nao-identificada-17","status":"publish","type":"tnc_col_329_item","link":"https:\/\/museuflorestal.ambiente.sp.gov.br\/acervo\/museu-florestal-octavio-vecchi\/disco-de-madeira-nao-identificada-17\/","title":{"rendered":"Disco de madeira n\u00e3o identificada"},"content":{"rendered":"<p>Corte transversal de tronco de madeira em formato irregular, fixado sobre base retangular com cor natural da madeira. Possui uma das faces envernizada e a outra natural, e casca ao redor. Na face envernizada h\u00e1 a inscri\u00e7\u00e3o em baixo relevo &#8220;M37&#8221; na parte superior. Na parte superior da base h\u00e1 a inscri\u00e7\u00e3o em baixo relevo &#8220;M37&#8221;, a inscri\u00e7\u00e3o \u00e0 caneta &#8220;MTD-464&#8221;, e uma etiqueta com a inscri\u00e7\u00e3o \u00e0 l\u00e1pis &#8220;MTD-464&#8221;. Na parte inferior da base h\u00e1 dois parafusos fixados e tiras de tecido coladas.<\/p>\n","protected":false},"featured_media":12739,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","_links":{"self":[{"href":"https:\/\/museuflorestal.ambiente.sp.gov.br\/acervo\/wp-json\/wp\/v2\/tnc_col_329_item\/12738"}],"collection":[{"href":"https:\/\/museuflorestal.ambiente.sp.gov.br\/acervo\/wp-json\/wp\/v2\/tnc_col_329_item"}],"about":[{"href":"https:\/\/museuflorestal.ambiente.sp.gov.br\/acervo\/wp-json\/wp\/v2\/types\/tnc_col_329_item"}],"replies":[{"embeddable":true,"href":"https:\/\/museuflorestal.ambiente.sp.gov.br\/acervo\/wp-json\/wp\/v2\/comments?post=12738"}],"version-history":[{"count":0,"href":"https:\/\/museuflorestal.ambiente.sp.gov.br\/acervo\/wp-json\/wp\/v2\/tnc_col_329_item\/12738\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/museuflorestal.ambiente.sp.gov.br\/acervo\/wp-json\/wp\/v2\/media\/12739"}],"wp:attachment":[{"href":"https:\/\/museuflorestal.ambiente.sp.gov.br\/acervo\/wp-json\/wp\/v2\/media?parent=12738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}